{"id":66,"count":162,"description":"\u00bfBuscas mu\u00f1ecas sexuales femeninas realistas de tama\u00f1o real que se sientan como la piel? Nuestra colecci\u00f3n de mu\u00f1ecas mini y adultas te ofrece los dise\u00f1os m\u00e1s realistas y de alta calidad para satisfacer todos tus deseos. Sigue leyendo para descubrir qu\u00e9 mu\u00f1ecas sexuales femeninas son las mejores para ti.","link":"https:\/\/www.sexdollmini.com\/es\/collections\/female-sex-dolls\/","name":"Mu\u00f1ecas sexuales femeninas","slug":"female-sex-dolls","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":38,"_links":{"self":[{"href":"https:\/\/www.sexdollmini.com\/es\/wp-json\/wp\/v2\/product_cat\/66","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sexdollmini.com\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.sexdollmini.com\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.sexdollmini.com\/es\/wp-json\/wp\/v2\/product?product_cat=66"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}