{"id":19488,"date":"2025-11-08T06:59:52","date_gmt":"2025-11-08T14:59:52","guid":{"rendered":"https:\/\/www.sexdollmini.com\/?post_type=product&#038;p=19488"},"modified":"2026-07-07T18:21:37","modified_gmt":"2026-07-08T01:21:37","slug":"cassiopeia-68cm-micro-auburn-sex-doll","status":"publish","type":"product","link":"https:\/\/www.sexdollmini.com\/it\/prodotto\/cassiopeia-68cm-micro-auburn-sex-doll\/","title":{"rendered":"Bambola del sesso micro castana Cassiopeia da 68 cm"},"content":{"rendered":"<h2>Dettagli delle bambole del sesso<\/h2>\n<p>La bambola del sesso color castano \u00e8 minuscola, alta 68 cm. Ha una sola vagina, che supporta l&#039;inserimento. Questa micro bambola del sesso pu\u00f2 essere facilmente trasportata in uno zaino o in una valigia, rendendola pi\u00f9 facile da pulire e risparmiando notevolmente il tempo necessario per pulirla.<\/p>\n<p>Altezza: 68 cm<br \/>\nPeso: 6 kg<br \/>\nBusto: 37 cm<br \/>\nLa vita: 29 cm<br \/>\nAnca: 44 cm<br \/>\nProfondit\u00e0 vaginale: 11 cm<\/p>\n<p>&nbsp;<\/p>\n<p>Si prega di considerare 2-4 cm di differenza nella misurazione manuale.<\/p>","protected":false},"excerpt":{"rendered":"<p>La pelle abbronzata della bambola del sesso la fa apparire pi\u00f9 sana e anche le proporzioni del suo corpo sono molto buone, il che spiega perch\u00e9 viene definita una bellezza.<\/p>","protected":false},"featured_media":19489,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[48,74,49,18,81,24,27,23,70,28,30,38,73,41,82,79,39,66,80,40,31,69,32,77,25,33,29,20,148,21,34,72,19,42,71,76,36,35,84,61,75,37,78],"product_tag":[],"class_list":["post-19488","product","type-product","status-publish","has-post-thumbnail","product_cat-65cm-sex-dolls","product_cat-6ye-doll","product_cat-70cm-sex-dolls","product_cat-adult-doll","product_cat-aibei-doll","product_cat-american-sex-doll","product_cat-anime-sex-dolls","product_cat-asian-sex-doll","product_cat-axb-doll","product_cat-blonde-sex-doll","product_cat-cheap-sex-doll","product_cat-chubby-sex-dolls","product_cat-climax-doll","product_cat-curvy-sex-dolls","product_cat-dolls-castle","product_cat-elsa-babe","product_cat-fantasy-sex-doll","product_cat-female-sex-dolls","product_cat-fire-doll","product_cat-full-body-sex-dolls","product_cat-full-size-sex-dolls","product_cat-girl-sex-dolls","product_cat-hentai-sex-dolls","product_cat-irontech-sex-dolls","product_cat-japanese-sex-dolls","product_cat-life-like-sex-dolls","product_cat-life-size-sex-dolls","product_cat-love-doll","product_cat-midget-sex-doll","product_cat-miniature-sex-doll","product_cat-petite-sex-dolls","product_cat-qita-doll","product_cat-real-doll","product_cat-skinny-sex-dolls","product_cat-sy-doll","product_cat-tantaly-sex-doll","product_cat-teen-sex-dolls","product_cat-tiny-sex-dolls","product_cat-tpe-sex-dolls","product_cat-us-stock-sex-dolls","product_cat-wm-doll","product_cat-young-sex-dolls","product_cat-zelex-doll","first","instock","sale","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product\/19488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/comments?post=19488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/media\/19489"}],"wp:attachment":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/media?parent=19488"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product_brand?post=19488"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product_cat?post=19488"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product_tag?post=19488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}