{"id":21,"count":146,"description":"Entra in un mondo di piacere compatto con la nostra collezione di bambole del sesso in miniatura. Progettate per la discrezione, la fantasia e la soddisfazione intima, queste piccole ma potenti compagne sono progettate per stupire in ogni modo.","link":"https:\/\/www.sexdollmini.com\/it\/collections\/miniature-sex-doll\/","name":"Bambola del sesso in miniatura","slug":"miniature-sex-doll","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":52,"_links":{"self":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product_cat\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.sexdollmini.com\/it\/wp-json\/wp\/v2\/product?product_cat=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}