{"id":44,"count":119,"description":"I\u0161\u010dete realizem v drobni obliki? Na\u0161e majhne seks lutke za prsi zdru\u017eujejo mehko estetiko z vrhunskimi detajli \u2013 izdelane so tako, da ustrezajo tistim, ki cenijo subtilne obline in intimen dizajn.","link":"https:\/\/www.sexdollmini.com\/sl\/collections\/small-breast-sex-doll\/","name":"Majhne prsi Spolna lutka","slug":"small-breast-sex-doll","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":62,"_links":{"self":[{"href":"https:\/\/www.sexdollmini.com\/sl\/wp-json\/wp\/v2\/product_cat\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sexdollmini.com\/sl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.sexdollmini.com\/sl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.sexdollmini.com\/sl\/wp-json\/wp\/v2\/product?product_cat=44"}],"curies":[{"name":"delovni list","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}